{"id":7453,"date":"2019-04-20T18:32:37","date_gmt":"2019-04-20T16:32:37","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=7453"},"modified":"2019-04-20T18:32:37","modified_gmt":"2019-04-20T16:32:37","slug":"nada-por-encima-de-la-constitucion-oviedo-198o","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2019\/04\/20\/nada-por-encima-de-la-constitucion-oviedo-198o\/","title":{"rendered":"\u00a1\u00a1 &#8221; NADA POR ENCIMA DE LA CONSTITUCI\u00d2N&#8221;: OVIEDO, 198O !!"},"content":{"rendered":"<p><strong>El primer paso tras las Elecciones Generales es orden el andamiaje legal y pol\u00ectico en Espa\u00f1a, para que, mirando al futuro, dejemos todo lo podrido generado en el gobierno de Rajoy, que desean continuar la extrema derecha, y poner en orden el camino para la Federaci\u00f2n de las Autonom\u00ecas y que nadie pretenda ir por fuera de la Constituci\u00f2n.<\/strong><\/p>\n<p><strong>Eso lleva a poner orden entre los involucionistas y los nacionalistas que creen que la Constituci\u00f2n puede saltarse a &#8220;la torera&#8221;.<\/strong><\/p>\n<p><strong>Es inaceptable que en 2019, exista la llamada&#8221; Policia Patri\u00f2tica&#8221;, que solamente en un mente enferma como la de Jorge Fern\u00e0ndez D\u00ecaz se pudo crear.\u00bf Que es eso de la policia patriotica?. \u00bfAlguien tiene la exclusividad de la Patria, de la bandera, de los himnos?.<\/strong><strong>.Muchos se llenan la boca con esas palabras.<\/strong><\/p>\n<p><strong>Los Billy el Ni\u00f1o y compa\u00f1\u00eca, los represores del franquismo vivos que viven del sistema: &#8220;la policia patri\u00f2tica&#8221; que sacaron del sombrero personajaes del siglo pasado. Corrupci\u00f2n en todas las formaciones que no caben en el futuro del pa\u00ecs.<\/strong><\/p>\n<p><strong>Grande Markaska, declar\u00f2 hoy en su campa\u00f1a elecctoral que el Partido Socialista Obrero Espa\u00f1ol, si triunfa quitar\u00e0 las medallas y prebendas de la &#8221; policia patr\u00f2tica&#8221;.<\/strong><\/p>\n<p><strong>Aprendamos de otros paises. Poner a la cabeza de todoS \u00a0el ejemplo, de la honestidad, de los principios del trabajo, para poner en movimiento a la Espa\u00f1a de nuestros hijos y nietos, es una taraea que debe de salir de28 de abril.<\/strong><\/p>\n<p><strong>&#8220;Nada por encima de la Constituci\u00f2n&#8221; declar\u00f2 en su toma de posesi\u00f2n un asturiano al tomar posesi\u00f2n de su puesto de Presidente del Principado de Asturias.Ni coches, ni guardaespaldas, sin cobrar el sueldo de Presidente por que ya ten\u00eca el de senador, como marcan los principios del partido m\u00e0s antiguo, pero m\u00e0s s\u00f2lido de Espa\u00f1a, el \u00f9nico capaz de enfrentar ele futuro, el Partido Socialista Obrero Espa\u00f1ol.<\/strong><\/p>\n<p><strong>Presente en el acto en la Diputaci\u00f2n, aquel hombre mayor dej\u00f2 muy claro, en su discurso, algo que es realmente fundamental..<\/strong><\/p>\n<p><strong>&#8220;NADA POR ENCIMA DE LA CONSTITUCION&#8221;. Hay que abrirla y reformarla en forma colectiva para que nos sirva para otros 30 a\u00f1os.<\/strong><\/p>\n<p><strong>Nadie se ha puesto a pensar, o pocos, pero \u00bf Que pasar\u00eca si faltase Felipe VI?. Al no haber cambiado la Ley Salica en la Constituci\u00f2n aabriria una brecha en la Jefatura del Estado. Se imaginan al jovencito\u00a0 Froylan como Jefe del Estado.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El primer paso tras las Elecciones Generales es orden el andamiaje legal y pol\u00ectico en Espa\u00f1a, para que, mirando al futuro, dejemos todo lo podrido generado en el gobierno de Rajoy, que desean continuar la extrema derecha, y poner en orden el camino para la Federaci\u00f2n de las Autonom\u00ecas y que nadie pretenda ir por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7453"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=7453"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7453\/revisions"}],"predecessor-version":[{"id":7455,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7453\/revisions\/7455"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=7453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=7453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=7453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}