{"id":7500,"date":"2019-04-23T17:44:48","date_gmt":"2019-04-23T15:44:48","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=7500"},"modified":"2019-04-23T17:44:48","modified_gmt":"2019-04-23T15:44:48","slug":"el-proceso-de-andres-uno-de-los-indecisos","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2019\/04\/23\/el-proceso-de-andres-uno-de-los-indecisos\/","title":{"rendered":"\u00a1\u00a1EL PROCESO DE ANDRES, UNO DE LOS INDECISOS !!"},"content":{"rendered":"<p><strong>Bueno, estamos a cuatro horas y medio del segundo debate.En ese marco voy a darle continuidad a mi indeciso de ayer, en ambos casos respetuando totalmente sus comentarios.<\/strong><\/p>\n<p><strong>Tras el prirmer debate ayer en RTVE, Andr\u00e8s que ten\u00eca duda y que expresaba la importancia de votar pero que requer\u00eca verlos a la cara,escucharlos, lo hizo acompa\u00f1ado de su esposa sus dos hijas y la perrita familiar.<\/strong><\/p>\n<p><strong>Hoy me permit\u00ec preguntarle si el debate de ayer le hab\u00eca definido su voto(por supuesto en ning\u00f9n momento hablando de nombres ni de su voluntad) y me di\u00f2 su autorizaci\u00f2n.<\/strong><\/p>\n<p><strong>Me dijo que el primer debate le servi\u00f2 para eliminar a dos, quedando su voto pendiente de el debate de hoy.<\/strong><\/p>\n<p><strong>Andr\u00e8s desech\u00f2 a dos que enfrentados por lo que hicieron en el pasado los dej\u00f2 definitivamente fuera.<\/strong><\/p>\n<p><strong>&#8221; Me falta por definir entre los otros dos&#8221;. &#8221; Ayer Pablo Iglesias me pareci\u00f2 coherente y que hablaba en realidades sin enfrentamientos&#8221;, me dijo.<\/strong><\/p>\n<p><strong>Y para no coartar su libertad, ah\u00ec pare la conversaci\u00f2n.<\/strong><\/p>\n<p><strong>Que haya pronunciado el nombre de Pablo Iglesias por algo surgi\u00f2, pero su voto estar\u00e0 entre dos, habiendo marginado a los dos primeros.<\/strong><\/p>\n<p><strong>Me di\u00f2 la impresi\u00f2n de que es una persona que no le satisfizo el bipartidismo y que se inclinar\u00e0 por uno de los dos emergentes(por supuesto no pareci\u00f2 en su razonamiento hablar para nada de Vox ).<\/strong><\/p>\n<p><strong>\u00bfCuantas mujeres y hombres del pa\u00ecs, estar\u00e0n en la caso de Andr\u00e8s?.<\/strong><\/p>\n<p><strong>Por ello, al hacer el partido de ida y vuelta, para el el primer tiempo le elimin\u00f2 a la mitad y en el segundo partido ,hoy, posiblemente termine de decidirse.<\/strong><\/p>\n<p><strong>Hablo de una persona que votar\u00e0.52 a\u00f1os, clase media, hombre con una trayectoria\u00a0 de trabajo importante, pero que por causa de alguna enfermedad, ya pasada, ahora tiene un trabajo m\u00e0s tranquilo.<\/strong><\/p>\n<p><strong>Agradezco a Andr\u00e8s su colabaoraci\u00f2n, para poder trasmitir lo m\u00e0s objetivamente su pensamiento a las 17.41 del martes 23 de abril.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Bueno, estamos a cuatro horas y medio del segundo debate.En ese marco voy a darle continuidad a mi indeciso de ayer, en ambos casos respetuando totalmente sus comentarios. Tras el prirmer debate ayer en RTVE, Andr\u00e8s que ten\u00eca duda y que expresaba la importancia de votar pero que requer\u00eca verlos a la cara,escucharlos, lo hizo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7500"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=7500"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7500\/revisions"}],"predecessor-version":[{"id":7503,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7500\/revisions\/7503"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=7500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=7500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=7500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}