{"id":7585,"date":"2019-04-28T21:28:24","date_gmt":"2019-04-28T19:28:24","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=7585"},"modified":"2019-04-28T21:28:24","modified_gmt":"2019-04-28T19:28:24","slug":"oriol-junqueras-desde-la-carcel-hace-talco-a-puigdemeont-y-a-ciudadanos-y-sera-clave-en-gobierno-nacional","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2019\/04\/28\/oriol-junqueras-desde-la-carcel-hace-talco-a-puigdemeont-y-a-ciudadanos-y-sera-clave-en-gobierno-nacional\/","title":{"rendered":"\u00a1\u00a1ORIOL JUNQUERAS, DESDE LA CARCEL, HACE TALCO A PUIGDEMEONT Y A CIUDADANOS Y SER\u00c0 CLAVE EN GOBIERNO NACIONAL !!"},"content":{"rendered":"<p><strong>Faltan los resultados oficiales, pero es digno de se\u00f1alar que un hombre cristiano, consecuente, en la c\u00e0rcel desde hace meses, del nacionalismo hist\u00f2rico de Catalu\u00f1a,\u00a0 que no la derecha de Puigdemont y Torra, los sondeos y las encuestas le dan 13 o 14 esca\u00f1os, liquidando as\u00ec a Puigdemont(en el &#8220;exilio&#8221;), y a Ciudadanos y a la se\u00f1ora Arrimadas.<\/strong><\/p>\n<p><strong>Se trata del &#8220;gordito&#8221; aquel que los policias cuando lo detuvieron dijeron que se cuidase en la camioneta que lo conduc\u00eca a la c\u00e0rcel, llamado\u00a0Oriol\u00a0\u00a0Junqueras.<\/strong><\/p>\n<p><strong>En dos telediarios Junqueras va a ser el presidente de Catalu\u00f1a y va ser clave la politica de di\u00e0logo que tendr\u00e0 que tener con Pedro S\u00e0nchez para ultimar su llegada a La Moncloa.Aunque todav\u00eca no se dan los resultados finales, el PSOE,con UP y PNV no alcanzan los 176 y ERC ser\u00e0 clave.<\/strong><\/p>\n<p><strong>Junqueras est\u00e0 realizando una pol\u00ectica de dialogo, para buscar una salida negociada que tendr\u00e0 que pasar por la Reforma de la Constituci\u00f2n.<\/strong><\/p>\n<p><strong>No es asunto menor, pero a veces nos olvidamos que si algo le pasase a Felipe VI, su hija no podr\u00e0 ser la reina por la Ley S\u00e0lica,\u00a0 creandose un proceso desestabilizador en la Jefatura del Estado, un elemento m\u00e0s para buscar una soluci\u00f2n negociada para Reformar la Constituci\u00f2n.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Faltan los resultados oficiales, pero es digno de se\u00f1alar que un hombre cristiano, consecuente, en la c\u00e0rcel desde hace meses, del nacionalismo hist\u00f2rico de Catalu\u00f1a,\u00a0 que no la derecha de Puigdemont y Torra, los sondeos y las encuestas le dan 13 o 14 esca\u00f1os, liquidando as\u00ec a Puigdemont(en el &#8220;exilio&#8221;), y a Ciudadanos y a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7585"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=7585"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7585\/revisions"}],"predecessor-version":[{"id":7588,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7585\/revisions\/7588"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=7585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=7585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=7585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}