{"id":7594,"date":"2019-04-29T08:22:57","date_gmt":"2019-04-29T06:22:57","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=7594"},"modified":"2019-04-29T08:22:57","modified_gmt":"2019-04-29T06:22:57","slug":"en-asturias-la-derecha-caesobre-todo-en-gijony-la-izquierda-resulta-vencedora","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2019\/04\/29\/en-asturias-la-derecha-caesobre-todo-en-gijony-la-izquierda-resulta-vencedora\/","title":{"rendered":"\u00a1\u00a1EN ASTURIAS LA DERECHA CAE,SOBRE TODO EN GIJON,Y LA IZQUIERDA RESULTA VENCEDORA !!"},"content":{"rendered":"<p><strong>Asturias se sum\u00f2 al triunfo de la izquierda a nivel nacional. El PSOE tendr\u00e0 tres esca\u00f1os, uno Unidas Podemos, y uno el PP,C`s y Vox.<\/strong><\/p>\n<p><strong>Cabe destacar el desplome deel Partido Popular en Gij\u00f2n, lo que hace presagiar que para mayo sera la izquierda la que gobierne y podr\u00e0 recuperar Gij\u00f2n.<\/strong><\/p>\n<p><strong>Fern\u00e0ndez habr\u00e0 observado el triunfo de su archienemigo Pedro Sanchez y confirmamos que Alvarez Cascos y Javier Fern\u00e0ndez han terminado su carrera pol\u00ectica, de la peor forma.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Asturias se sum\u00f2 al triunfo de la izquierda a nivel nacional. El PSOE tendr\u00e0 tres esca\u00f1os, uno Unidas Podemos, y uno el PP,C`s y Vox. Cabe destacar el desplome deel Partido Popular en Gij\u00f2n, lo que hace presagiar que para mayo sera la izquierda la que gobierne y podr\u00e0 recuperar Gij\u00f2n. Fern\u00e0ndez habr\u00e0 observado el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7594"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=7594"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7594\/revisions"}],"predecessor-version":[{"id":7597,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7594\/revisions\/7597"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=7594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=7594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=7594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}