{"id":4017,"date":"2018-06-30T07:26:55","date_gmt":"2018-06-30T05:26:55","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/retorcida-realidad\/?p=4017"},"modified":"2018-06-30T07:28:01","modified_gmt":"2018-06-30T05:28:01","slug":"a-la-tercera","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/2018\/06\/30\/a-la-tercera\/","title":{"rendered":"A la tercera."},"content":{"rendered":"<p><a href=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/4\/2018\/06\/27628758-koBH-624x416@El-Comercio.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-4019 alignleft\" src=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/4\/2018\/06\/27628758-koBH-624x416@El-Comercio-300x200.jpg\" alt=\"27628758-kobh-624x416el-comercio\" width=\"300\" height=\"200\" srcset=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/4\/2018\/06\/27628758-koBH-624x416@El-Comercio-300x200.jpg 300w, https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/4\/2018\/06\/27628758-koBH-624x416@El-Comercio.jpg 624w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>S\u00ed, por fin, el Plan General de Ordenaci\u00f3n (PGO) ha sido aprobado de forma provisional por el Ayuntamiento. Sin duda, es la buena noticia de la semana. Ha sido a la tercera, tras dos pasos anteriores por el Pleno (febrero de 2016 y septiembre de 2017), y con mayor grado de consenso entre los grupos municipales. En realidad, esto se debe a que el PSOE esta vez se abstuvo, mientras que en anteriores ocasiones hab\u00eda votado en contra. <strong>Una postura, la verdad, que nunca nadie entendi\u00f3 muy bien.<\/strong> El caso es que este PGO tiene una virtud sobre los anulados: no se mete en honduras. <strong>Trata de ser simple y evita abrir pol\u00e9micas como sucedi\u00f3, por ejemplo, con el \u00abplan Teixidor\u00bb (2007) que introdujo en nuestras vidas el concepto de \u00ab<em>Urbs in rure<\/em>\u00bb<\/strong>: ya saben, aquello de que la ciudad invad\u00eda el campo que produjo hasta manifestaciones. Caro nos cost\u00f3. La noche negra del urbanismo gijon\u00e9s empez\u00f3 ah\u00ed cuando fue tumbado por los tribunales y el siguiente en la misma l\u00ednea, tambi\u00e9n conocido como el \u00abplan Sanjurjo\u00bb (2011), corri\u00f3 la misma suerte. <strong>M\u00e1s de una d\u00e9cada, pues, sin un planeamiento urban\u00edstico firme para esta ciudad que se ha hecho muy larga<\/strong>.<\/p>\n<p>El\u00a0 nuevo PGO, como digo, tiene la virtud de la sencillez. <strong>No abre grandes bolsas de suelo -porque no se necesitan- y busca el equilibrio con actuaciones m\u00e1s blandas.<\/strong> Aquellos residenciales fara\u00f3nicos (Cabue\u00f1es, Castiello, Porceyo o Granda) se han visto cercenados o muy mermados. E<strong>l Gij\u00f3n actual es bien distinto y eso tiene su reflejo. No necesita crecimientos agresivos puesto que se est\u00e1 tendiendo m\u00e1s hacia la rehabilitaci\u00f3n.<\/strong> El n\u00famero de edificios de nueva construcci\u00f3n sigue siendo bastante moderado, mientras que las reformas no paran de crecer. <strong>El que sea un plan, llam\u00e9moslo as\u00ed, \u00ablight\u00bb, tambi\u00e9n se nota cuando tiene que afrontar cuestiones escabrosas.<\/strong> Me refiero al suelo del antiguo astillero de Naval Gij\u00f3n al que se le quiere transformar en un parque empresarial -\u00abAd gloriam\u00bb a la lucha obrera que all\u00ed tuvo lugar- evitando as\u00ed cualquier uso residencial. El tiempo dir\u00e1, en funci\u00f3n de cu\u00e1nto tarde en desarrollarse esta zona del Natahoyo, si ha sido una buena decisi\u00f3n o no. Lo mismo que la renuncia a la v\u00eda expropiatoria en el \u00e1mbito del Rick\u2019s, pidiendo a sus propietarios que \u00ab<em>adapten su est\u00e9tica a los tiempos actuales<\/em>\u00bb para evitar los tribunales.<strong> En resumen, conflictos en este planteamiento, a la postre, cero.<\/strong> Ahora, s\u00f3lo falta que este nuevo PGO sea enviado en los pr\u00f3ximos d\u00edas a la Comisi\u00f3n de Urbanismo y Ordenaci\u00f3n del Territorio de Asturias (CUOTA). El organismo del Principado tiene cuatro meses para revisarlo y emitir los correspondientes informes. <strong>S\u00f3lo faltaba que la CUOTA, que no dijo ni mu en los desastres anteriores, le pusiese pegas.<\/strong><\/p>\n<p><em><strong>@balbuenajm<\/strong> <\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>S\u00ed, por fin, el Plan General de Ordenaci\u00f3n (PGO) ha sido aprobado de forma provisional por el Ayuntamiento. Sin duda, es la buena noticia de la semana. Ha sido a la tercera, tras dos pasos anteriores por el Pleno (febrero de 2016 y septiembre de 2017), y con mayor grado de consenso entre los grupos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[373,48,17,193,374,264,26],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/posts\/4017"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/comments?post=4017"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/posts\/4017\/revisions"}],"predecessor-version":[{"id":4020,"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/posts\/4017\/revisions\/4020"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/media?parent=4017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/categories?post=4017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/retorcida-realidad\/wp-json\/wp\/v2\/tags?post=4017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}