{"id":1056,"date":"2019-04-02T11:43:35","date_gmt":"2019-04-02T09:43:35","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=1056"},"modified":"2019-04-02T11:43:35","modified_gmt":"2019-04-02T09:43:35","slug":"distrito-azul","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2019\/04\/02\/distrito-azul\/","title":{"rendered":"&#8216;Distrito azul&#8217;"},"content":{"rendered":"<p>Aunque se pueda llegar a pensar que el \u2018Distrito Azul\u2019 presentado por la marca municipal de promoci\u00f3n empresarial Impulsa encierra cierto oportunismo electoral, resulta positivo poner sobre la mesa un esbozo como el que hemos visto esta semana para abrir una reflexi\u00f3n acerca del futuro de los terrenos de Naval Gij\u00f3n. El estudio de la consultora contratada por el Ayuntamiento sobre las posibilidades de esa gran bolsa de suelo generada tras la desaparici\u00f3n del emblem\u00e1tico astillero supone un buen punto de partida para discutir de qu\u00e9 manera la ciudad pueda aprovechar esa notable zona del litoral gijon\u00e9s. Se parte de la base de que existe, al menos, un objetivo compartido mayoritariamente por todas las fuerzas pol\u00edticas para transformar ese espacio en un polo de econom\u00eda azul. El destino es acertado en cuanto que persigue revitalizar la ligaz\u00f3n de la villa con la actividad mar\u00edtima mediante la b\u00fasqueda de nuevos nichos de negocio que favorezcan el crecimiento y la creaci\u00f3n de empleo. Ahora bien, una vez definida esta meta es fundamental alcanzar el mayor consenso posible sobre la ruta que debemos emprender para alcanzarla. Por ello, el boceto planteado por el gobierno local es una buena forma de levantar el tel\u00f3n.<br \/>\nEl planteamiento es construir dos edificios de oficinas como los barcos de Poniente, habilitar una zona l\u00fadico-deportiva e instalar un campus de la mar en la antigua sede del astillero. La inversi\u00f3n calculada por la firma autora del estudio para esta transformaci\u00f3n supera los 47 millones de euros, sin incluir la compra de los terrenos propiedad del puerto y de la sociedad de reconversi\u00f3n Pymar. Con la adquisici\u00f3n del suelo, el coste total puede requerir un desembolso de 64 millones. La conclusi\u00f3n a la que llega la consultora es que la operaci\u00f3n es poco atractiva para la iniciativa privada ante la imposibilidad de edificar viviendas en alguna de las parcelas. Es decir, solo es factible la intervenci\u00f3n p\u00fablica porque el resultado final es deficitario.<br \/>\nEl proyecto, por lo tanto, es ahora mismo inasumible por el Ayuntamiento gijon\u00e9s tal como est\u00e1 planteado. No dispone de capacidad econ\u00f3mica suficiente para afrontar una actuaci\u00f3n de esta envergadura por s\u00ed solo, aunque dispongamos incluso de fondos procedentes de Europa para ayudar a su financiaci\u00f3n haciendo uso de los programas para promover este tipo de acciones en las ciudades costeras. La Administraci\u00f3n local tiene adquiridos unos compromisos de gasto para los pr\u00f3ximos a\u00f1os que pesan como una losa en sus cuentas. Decenas de millones pendientes para llevar adelante el plan de v\u00edas, la zona log\u00edstica, el desarrollo del plan de Tabacalera, la nueva Jefatura de Polic\u00eda, la compra de la finca de La Formigosa para ampliar el parque tecnol\u00f3gico, etc\u00e9tera.<br \/>\nSin embargo, se est\u00e1 a tiempo para introducir en el debate otras f\u00f3rmulas que impidan que la recuperaci\u00f3n de ese valioso y ampl\u00edsimo solar resulte gravosa para las arcas municipales. Quiz\u00e1s haya que buscar alg\u00fan modelo, consorcio, sociedad o lo que tenga que ser, que favorezca la participaci\u00f3n en el proyecto de quienes ahora son due\u00f1os de los predios. Porque puede que no se llegue a entender bien que un suelo en buena parte p\u00fablico tenga que ser adquirido con dinero de la hacienda de todos los gijoneses para una utilidad, al fin y al cabo, de inter\u00e9s igualmente general.<br \/>\nY tampoco se puede descartar de mano la correcci\u00f3n del plan urban\u00edstico recientemente aprobado para incluir en una franja la utilizaci\u00f3n residencial que ya se hab\u00eda visto necesaria con anterioridad durante el dise\u00f1o del PGO. Bien vale una enmienda si el objetivo que con ella se consigue es beneficioso para la ciudad.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aunque se pueda llegar a pensar que el \u2018Distrito Azul\u2019 presentado por la marca municipal de promoci\u00f3n empresarial Impulsa encierra cierto oportunismo electoral, resulta positivo poner sobre la mesa un esbozo como el que hemos visto esta semana para abrir una reflexi\u00f3n acerca del futuro de los terrenos de Naval Gij\u00f3n. El estudio de la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[955,956,213,957,408,455,489,490,915,738,606],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1056"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=1056"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1056\/revisions"}],"predecessor-version":[{"id":1057,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1056\/revisions\/1057"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=1056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=1056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=1056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}