{"id":1064,"date":"2019-05-08T09:11:38","date_gmt":"2019-05-08T07:11:38","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=1064"},"modified":"2019-05-08T09:11:38","modified_gmt":"2019-05-08T07:11:38","slug":"la-selva-sin-ley","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2019\/05\/08\/la-selva-sin-ley\/","title":{"rendered":"La selva sin ley"},"content":{"rendered":"<p>El auge de los pisos tur\u00edsticos se ha convertido en un peligroso enemigo para la hoteler\u00eda. El crecimiento vertiginoso que est\u00e1 experimentando este tipo de alojamientos amenaza con destrozar un sector en Asturias y en Gij\u00f3n, que a\u00fan sufre las consecuencias del tremendo desajuste en costes provocado por el desequilibrio entre oferta y demanda, la excesiva estacionalizaci\u00f3n y el cambio de h\u00e1bitos de los visitantes. Hace escasamente un mes, a las puertas de la Semana Santa, la patronal advert\u00eda de que la irrupci\u00f3n de viviendas de uso tur\u00edstico abocaba de forma irremediable a una reconversi\u00f3n de la actividad con la consiguiente p\u00e9rdida de puestos de trabajo. Una de las medidas que en algunos casos ya se ha empezado a acometer es la transformaci\u00f3n de hoteles en complejos de apartamentos para ofrecer una alternativa de calidad a los domicilios privados. Es la menos mala de cuantas se pueden adoptar, desde luego, aunque ello supone un sacrificio del nivel de empleo.<br \/>\nLa reacci\u00f3n empresarial se produce ante un fen\u00f3meno al que, hasta ahora, no se le ha puesto coto y cuyos efectos van m\u00e1s all\u00e1 de las consecuencias que genera en el negocio de las pernoctaciones. En muy poco tiempo, las plazas disponibles en Gij\u00f3n en este tipo de viviendas ha igualado a las que exist\u00edan en el cat\u00e1logo hotelero. Se trata de pisos registrados, legales, con su acreditaci\u00f3n para albergar visitantes y que, por lo tanto, est\u00e1n sometidos a la norma fijada al respecto por el Gobierno regional. Pero existe un buen n\u00famero de alojamientos que se escapan del control, ofrecidos de manera ilegal a trav\u00e9s de determinadas plataformas de internet, sin garant\u00edas para los usuarios y que est\u00e1 convirtiendo la actividad en una aut\u00e9ntica selva.<br \/>\nLos problemas generados por el aumento desmedido de los pisos tur\u00edsticos se llevan padeciendo desde hace unos a\u00f1os en otras ciudades del pa\u00eds sin que las medidas para evitarlos hayan tenido demasiado efecto. Adem\u00e1s de la repercusi\u00f3n directa en el negocio convencional, producen tambi\u00e9n impactos colaterales, como la incidencia en la vida vecinal, la alteraci\u00f3n en materia de seguridad o el incremento del precio de los alquileres ante la escasez de inmuebles para el arrendamiento tradicional. En Madrid o en Barcelona, la viviendas VUT est\u00e1n provocando incluso la transformaci\u00f3n de algunos barrios con el desplazamiento de sus residentes por el aterrizaje de fondos inmobiliarios e inversores extranjeros, buena parte de ellos procedentes de China y de Europa del Este, que adquieren edificios enteros para este tipo de estancias.<br \/>\nEn Gij\u00f3n la invasi\u00f3n no ha llegado todav\u00eda a tal extremo, pero el Ayuntamiento ha decidido plantar cara para intentar frenar la expansi\u00f3n de las residencias ilegales. La Corporaci\u00f3n aprob\u00f3 esta semana por unanimidad una iniciativa para poner en marcha actuaciones que permitan un mayor control de las viviendas destinadas al turismo que se escapan de la norma, al tiempo que emplaza a los ciudadanos a denunciar las situaciones que conozcan. La colaboraci\u00f3n vecinal, en este caso, es fundamental. Solo el que reside enfrente, arriba o abajo, sabe lo que ocurre en el inmueble. La Administraci\u00f3n no tiene capacidad para perseguir los pisos piratas uno a uno. Resulta imposible.<br \/>\nComo tambi\u00e9n resulta imposible acabar con el desmadre si cada municipio entabla la guerra por su cuenta, como est\u00e1 ocurriendo en todo el territorio nacional. Por ello urge una legislaci\u00f3n estatal que regule las VUT en todos sus aspectos para impedir la competencia desleal que se est\u00e1 produciendo y sirva de garant\u00eda jur\u00eddica para todas las partes, propietarios y usuarios. De la misma manera que existe una ley que ampara el arrendamiento tradicional, tiene que haber otra que establezca las reglas del juego en un campo ahora excesivamente bananero.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El auge de los pisos tur\u00edsticos se ha convertido en un peligroso enemigo para la hoteler\u00eda. El crecimiento vertiginoso que est\u00e1 experimentando este tipo de alojamientos amenaza con destrozar un sector en Asturias y en Gij\u00f3n, que a\u00fan sufre las consecuencias del tremendo desajuste en costes provocado por el desequilibrio entre oferta y demanda, la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[968,969,284,967,972,970,965,966,971],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1064"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=1064"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1064\/revisions"}],"predecessor-version":[{"id":1065,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1064\/revisions\/1065"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=1064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=1064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=1064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}