{"id":1093,"date":"2019-07-01T11:45:59","date_gmt":"2019-07-01T09:45:59","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=1093"},"modified":"2019-07-01T11:45:59","modified_gmt":"2019-07-01T09:45:59","slug":"ocio-y-cultura","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2019\/07\/01\/ocio-y-cultura\/","title":{"rendered":"Ocio y cultura"},"content":{"rendered":"<p>El ocio y la cultura se convierten en patas esenciales para la reinvenci\u00f3n de la ciudad que persigue el equipo de Ana Gonz\u00e1lez. Ambos instrumentos, llevados a su m\u00e1xima expresi\u00f3n, son canales de transmisi\u00f3n de la ideolog\u00eda pol\u00edtica, salvaguarda de valores muchas veces m\u00e1s eficaz que la propia educaci\u00f3n, y de ah\u00ed que cualquier cambio en el gobierno de turno de signo distinto al anterior suele conllevar una transformaci\u00f3n de los contenidos y de las maneras de llevar estas manifestaciones a la ciudadan\u00eda. En el pluralismo de su universalidad existe la izquierda y la derecha, aunque la mayor preocupaci\u00f3n en todo caso tiene que ser la utilizaci\u00f3n que se haga de los recursos p\u00fablicos para ponerlas al alcance de la gente.<br \/>\nLa nueva regencia local plantea el cambio mediante la ruptura para su reconstrucci\u00f3n desde el regreso al sistema de funcionamiento del pasado. Para ello la disoluci\u00f3n de Divertia resulta irrenunciable. La constituci\u00f3n de esta sociedad fue el mayor exponente de los mandatarios de Foro para aplicar un modelo de gesti\u00f3n distinto al que hubo durante la etapa socialista, pero tampoco los resultados fueron excepcionales para las arcas municipales. Al final se convirti\u00f3 en una entidad mastod\u00f3ntica con saldos dif\u00edcilmente soportables. No siempre la mezcla resulta exitosa. Ahora se plantea separar para volver al estadio anterior a la concentraci\u00f3n. De una sociedad se pasar\u00e1 otra vez a tres, con sus consejos de administraci\u00f3n y sus correspondientes asientos. Lo sustancial, por lo tanto, es adem\u00e1s de la mejora de la actividad, que exista una buena coordinaci\u00f3n, un control eficaz de los dineros y evitar que la organizaci\u00f3n genere peque\u00f1os reinos de taifas.<br \/>\nPrecisamente sobre cultura y ocio versaron las decisiones de la primera junta de gobierno presidida por la flamante alcaldesa. Eran asuntos que hab\u00edan quedado pendientes por parte de sus antecesores, que casualmente les toc\u00f3 resolver con su aprobaci\u00f3n a los actuales mandatarios y que protagonizar\u00e1n una buena parte de la actuaci\u00f3n pol\u00edtica en la materia que estamos comentando. El Ayuntamiento ha dado el visto bueno al sobrecoste originado en la rehabilitaci\u00f3n de la f\u00e1brica de tabacos por la aparici\u00f3n de los restos arqueol\u00f3gicos. Una modificaci\u00f3n presupuestaria sobrevenida que, sin embargo, no representa ninguna sorpresa porque como ya se sabe el barrio de Cimavilla es un cofre de la historia. Lo relevante de la medida, no obstante, es que las obras se vuelven a reactivar despu\u00e9s de casi un a\u00f1o paradas, mientras se vuelve a reflexionar sobre cu\u00e1l ser\u00e1 su destino como equipamiento cultural. Es decir, hacia donde se inclinar\u00e1 la balanza con la nueva corporaci\u00f3n. Si se dedicar\u00e1 a lo que ha venido planteando la plataforma c\u00edvica que quiere hacer de Tabacalera un sitio de muestra y creaci\u00f3n abierto al barrio y gestionado como una cooperativa o se atender\u00e1 a quienes consideran que el edificio tiene que albergar el museo de Gij\u00f3n, como reclamaron los directores de los recintos muse\u00edsticos en un manifiesto. A lo mejor se pueden compatibilizar ambos usos. En cualquier caso, el noble inmueble es patrimonio de la ciudad entera, no de un lugar, y por lo tanto tiene que servir para el disfrute de toda la ciudadan\u00eda.<br \/>\nY la segunda medida de la administraci\u00f3n fue la autorizaci\u00f3n para alquilar al puerto la parcela que ocupar\u00e1 la nueva edici\u00f3n de la Semana Negra. El festival vuelve a tener el amparo del Ayuntamiento gijon\u00e9s sin objeciones. Quiz\u00e1s sea el momento de repensar el certamen literario-popular para actualizarlo y recuperar br\u00edo, sin que ello suponga mayor dependencia del presupuesto municipal. M\u00e1s bien, al contrario.<br \/>\nEn estos a\u00f1os surgieron otras iniciativas de car\u00e1cter privado que han llenado la programaci\u00f3n con una capacidad de atracci\u00f3n indudable y un concepto acorde con los tiempos en los que estamos. Un ejemplo se est\u00e1 celebrando estos d\u00edas en el recinto ferial. Puede que entre los nuevos regidores haya alguien a quien se le ocurra poner en cuesti\u00f3n este tipo de ofertas, pero ser\u00eda una equivocaci\u00f3n hacerlo en tanto que el riesgo asumido sea ajeno y paguen lo que es debido por la ocupaci\u00f3n del suelo. Lo mismo sucede con el aterrizaje de un promotor de macroexposiciones en el Palacio de Revillagigedo. Bienvenido sea que alguien elija Gij\u00f3n para revitalizar tal espacio emblem\u00e1tico con muestras culturales y art\u00edsticas de gran consumo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El ocio y la cultura se convierten en patas esenciales para la reinvenci\u00f3n de la ciudad que persigue el equipo de Ana Gonz\u00e1lez. Ambos instrumentos, llevados a su m\u00e1xima expresi\u00f3n, son canales de transmisi\u00f3n de la ideolog\u00eda pol\u00edtica, salvaguarda de valores muchas veces m\u00e1s eficaz que la propia educaci\u00f3n, y de ah\u00ed que cualquier cambio [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[126,174,200,1017,1018,1015,1016,930],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1093"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=1093"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1093\/revisions"}],"predecessor-version":[{"id":1094,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1093\/revisions\/1094"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=1093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=1093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=1093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}