{"id":1198,"date":"2020-03-15T09:52:26","date_gmt":"2020-03-15T08:52:26","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=1198"},"modified":"2020-03-15T09:52:26","modified_gmt":"2020-03-15T08:52:26","slug":"los-sueldos-sociales","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2020\/03\/15\/los-sueldos-sociales\/","title":{"rendered":"Los sueldos sociales"},"content":{"rendered":"<p>Veamos en qu\u00e9 situaci\u00f3n se encuentran las prestaciones de subsistencia de los servicios sociales a expensas de que el Gobierno central lleve adelante la implantaci\u00f3n en todo el pa\u00eds del ingreso m\u00ednimo vital. En Gij\u00f3n, la izquierda est\u00e1 redise\u00f1ando la renta social creada durante la anterior corporaci\u00f3n con la intenci\u00f3n de lanzar una primera convocatoria el pr\u00f3ximo mes de abril. El funcionamiento ser\u00e1 distinto, por lo que han venido avanzando las partes que lo est\u00e1n cocinando, de tal manera que los comerciantes no tendr\u00e1n el protagonismo que adquirieron en el control del destino del dinero repartido por tarjeta prepago entre los beneficiarios. El modelo cambiar\u00e1 y, al parecer, tambi\u00e9n los objetivos si es que finalmente se incluyen itinerarios de formaci\u00f3n y empleo para los perceptores y el pago de los alquileres. Al fin y al cabo, cuando se trata de cubrir las necesidades b\u00e1sicas, el techo es prioritario.<br \/>\nPor otro lado, la nueva ley que se est\u00e1 tramitando en el Parlamento asturiano que regular\u00e1 las prestaciones del Principado, entre ellas el salario social, tardar\u00e1 a\u00fan un a\u00f1o m\u00ednimo en entrar en vigor. La normativa elevar\u00e1 el importe de la paga y, por lo tanto, el coste del sistema, que ya supera los 120 millones de euros. Adem\u00e1s, incluir\u00e1 como derecho subjetivo que quien reciba el salario pueda acceder directamente a la ayuda al arrendamiento del piso, que es tanto como garantizar la cobertura ampliada.<br \/>\nSin embargo resulta curioso, porque as\u00ed de tozuda es la realidad, que casi la mitad de quienes obtuvieron las ayudas al alquiler de la Empresa Municipal de la Vivienda fueran precisamente gente que trabaja. Personas con empleos precarios que cobran un sueldo \u00ednfimo, incluso por debajo de aquellos que buenamente reciben la paga de la Administraci\u00f3n. La ley que est\u00e1 llamada a blindar el salario social, como sostienen quienes la inspiran, no aclara las medidas que eviten que el sustento sea eterno. Se vuelve a correr el riesgo de mantener la cronificaci\u00f3n de la pobreza bajo el amparo de un subsidio que tendr\u00eda que estar mucho m\u00e1s vinculado a la integraci\u00f3n en el mercado de trabajo. El dilema ahora es qu\u00e9 suceder\u00e1 con la renta social gijonesa y con el salario social del Principado cuando el Gobierno de S\u00e1nchez-Iglesias ponga en marcha la prestaci\u00f3n nacional. La intenci\u00f3n es que el \u00edngreso m\u00ednimo vital, anunciado por el vicepresidente y ratificado por el ministro Jos\u00e9 Luis Escriv\u00e1, est\u00e9 listo ya el pr\u00f3ximo a\u00f1o para su implantaci\u00f3n paulatina a lo largo de la legislatura. Ser\u00e1 un subsidio de la Seguridad Social, que podr\u00eda compatibilizarse con el cobro de un sueldo o de otras prestaciones p\u00fablicas, de tal que manera que se garantice un ingreso total al mes igual al indicador de renta media que se establezca. El coste, cerca de 10.000 millones de euros, que colgar\u00edan de los presupuestos generales del Estado.<br \/>\nEl Ejecutivo de coalici\u00f3n quiere que el \u00edngreso m\u00ednimo vital sea coordinado con aquellos otros sistemas que ya est\u00e1n vigentes en comunidades aut\u00f3nomas y ayuntamientos, como es el caso de Gij\u00f3n. Est\u00e1 por saber s\u00ed ser\u00e1n complementarios o si lo m\u00e1s l\u00f3gico es que algunos de ellos desaparezca. Lo que no tiene ning\u00fan sentido es que existan tres sueldos sociales cuando ya solo con uno se ha desincentivado la b\u00fasqueda de empleo.<\/p>\n<p>Postdata: Al final se impuso la sensatez. Los grupos pol\u00edticos de la Corporaci\u00f3n gijonesa aprobar\u00e1n por unanimidad la declaraci\u00f3n institucional para apoyar la candidatura de la Universidad Laboral como Patrimonio de la Humanidad. En el texto que ir\u00e1 al Pleno se recogen los or\u00edgenes, l\u00f3gicamente inmodificables, la riqueza art\u00edstica del conjunto arquitect\u00f3nico, la acertada rehabilitaci\u00f3n y su transformaci\u00f3n en referente educativo, cient\u00edfico y cultural. Es incomprensible que para llegar hasta aqu\u00ed se organizara tanto l\u00edo. Alguien en el equipo de gobierno tuvo que aprender la lecci\u00f3n. De todas formas, sostienen los partidos firmantes que la declaraci\u00f3n por la Unesco \u00abcontribuir\u00e1 al proceso de resignificaci\u00f3n del edificio\u00bb, cuando la resignificaci\u00f3n, por mucho que se empe\u00f1en los pol\u00edticos, ya est\u00e1 hecha.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Veamos en qu\u00e9 situaci\u00f3n se encuentran las prestaciones de subsistencia de los servicios sociales a expensas de que el Gobierno central lleve adelante la implantaci\u00f3n en todo el pa\u00eds del ingreso m\u00ednimo vital. En Gij\u00f3n, la izquierda est\u00e1 redise\u00f1ando la renta social creada durante la anterior corporaci\u00f3n con la intenci\u00f3n de lanzar una primera convocatoria [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1198"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"predecessor-version":[{"id":1199,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/1198\/revisions\/1199"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}