{"id":886,"date":"2018-03-04T16:48:01","date_gmt":"2018-03-04T15:48:01","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=886"},"modified":"2018-03-04T16:57:28","modified_gmt":"2018-03-04T15:57:28","slug":"los-valores-del-hombre","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2018\/03\/04\/los-valores-del-hombre\/","title":{"rendered":"Los valores del hombre"},"content":{"rendered":"<p>Ese enorme coraz\u00f3n que Quini ten\u00eda para todo lo que representaba su vida no pudo soportar el trallazo de la muerte, pero su latido perdurar\u00e1 para siempre en la memoria colectiva de una ciudad con los colores a los que tanto am\u00f3. El Brujo se nos fue de un latigazo atroz sin previo aviso, a traici\u00f3n, aunque semejante golpe no ha conseguido, no conseguir\u00e1 jam\u00e1s, arrebatar el c\u00famulo de valores que encarn\u00f3 Enrique de Castro a lo largo de su trayectoria personal y deportiva. Ese es el legado que tenemos que preservar. Un tratado para las relaciones humanas en toda regla que se construye por s\u00ed solo recorriendo su figura.<\/p>\n<p><a href=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/26\/2018\/03\/Quini-e1520178930736.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-888\" src=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/26\/2018\/03\/Quini-300x224.jpg\" alt=\"quini\" width=\"300\" height=\"224\" \/><\/a><\/p>\n<p>Desde el fat\u00eddico martes que Quini nos dej\u00f3 hemos ido reflejando a trav\u00e9s de las p\u00e1ginas de este peri\u00f3dico el cuerpo doctrinal de esa herencia mediante m\u00faltiples an\u00e1lisis, testimonios y vivencias de personas que desde la constataci\u00f3n, el sentimiento o la admiraci\u00f3n contribuyen a la creaci\u00f3n de ese relato. Basta con la recopilaci\u00f3n de los adjetivos que se han utilizado en esas narraciones con el fin de expresar sus cualidades para reforzar la idea que ya ten\u00edamos del hombre del que estamos hablando. Yo lo he hecho y me he encontrado con m\u00e1s de un centenar de palabras cuya enumeraci\u00f3n en su totalidad no tendr\u00eda espacio suficiente en este art\u00edculo, pero considero enriquecedor extraer algunas de ellas como mero recordatorio de la dimensi\u00f3n del exfutbolista. Del Quini jugador hemos le\u00eddo que era soberbio, valiente, implacable, astuto, incontenible, cl\u00e1sico, poderoso, fr\u00edo, regateador, ambicioso, torero, cabeceador, goleador, pichichi, deportivo, compa\u00f1ero. Del Quini astro del f\u00fatbol se ha dicho que era maestro, mago, majestuoso, carism\u00e1tico, hist\u00f3rico, popular, universal, gigante, colosal, legendario, irrepetible, eterno.<br \/>\nDel Quini persona la lista de calificativos es interminable: cercano, encantador, simp\u00e1tico, cari\u00f1oso, excepcional, extraordinario, sensacional, respetuoso, sencillo, sincero, fraternal, humilde, agradecido, caballeroso, amable, entra\u00f1able, emp\u00e1tico, alegre, bromista, socarr\u00f3n, generoso, solidario, desprendido, natural, bueno, paisanu.<br \/>\nNo resulta extra\u00f1o, por lo tanto, que con toda esa bonhom\u00eda Enrique de Castro se convirtiera en un \u00eddolo de carne y hueso, en el dios que algunos aficionados llegaron a colocar en sus camisetas sobre el \u20189\u2019 del dorsal. Un dios terrenal del que nos queda su recuerdo y ese conjunto de virtudes que le hicieron tan singular.<br \/>\nLa primera reacci\u00f3n oficial para honrar su memoria fue apellidar El Molin\u00f3n con su nombre. Ni un segundo tardaron los pol\u00edticos en ponerse de acuerdo para rebautizar el templo rojiblanco, a\u00f1adi\u00e9ndolo a la relaci\u00f3n de elementos con la denominaci\u00f3n c\u00f3mplice del m\u00edtico ariete, como el parque, la avenida o los trofeos a los que siguen su estela que todos los a\u00f1os otorga EL COMERCIO con la participaci\u00f3n de las pe\u00f1as y que tanta ilusi\u00f3n le generaba. Unos galardones que en el fondo tambi\u00e9n ven\u00edan a demostrar sus bondades.<br \/>\nEstos d\u00edas, desde la emoci\u00f3n producida ante la inmensa sensaci\u00f3n de orfandad, surgi\u00f3 un manantial de iniciativas en honor a su figura: una escultura en la rotonda junto al campo municipal con la imagen de Ubaldo Puche que ilustr\u00f3 la portada de este diario el pasado mi\u00e9rcoles, un busto en el t\u00fanel de vestuarios, un encuentro de la selecci\u00f3n espa\u00f1ola en Gij\u00f3n, otro entre el Sporting y el Bar\u00e7a y un c\u00e1ntico desde las gradas con el \u00a1Ahora Quini, ahora! en cada minuto nueve son algunas de esas propuestas.<br \/>\nTodas resultan bienvenidas, pero adem\u00e1s de incrementar el santuario tenemos la responsabilidad de seguir trasmitiendo ese compendio de valores que Enrique de Castro llev\u00f3 m\u00e1s all\u00e1 del f\u00fatbol para que las generaciones venideras, aquellas que no tuvieron la oportunidad de disfrutar de su presencia, conozcan y practiquen lo que Quini realmente representa. Ese ser\u00eda, a buen seguro, su mayor de los deseos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ese enorme coraz\u00f3n que Quini ten\u00eda para todo lo que representaba su vida no pudo soportar el trallazo de la muerte, pero su latido perdurar\u00e1 para siempre en la memoria colectiva de una ciudad con los colores a los que tanto am\u00f3. El Brujo se nos fue de un latigazo atroz sin previo aviso, a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[762,763,212,764,761,284,760,745],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/886"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/886\/revisions"}],"predecessor-version":[{"id":891,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/886\/revisions\/891"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}