{"id":913,"date":"2018-04-29T18:59:45","date_gmt":"2018-04-29T16:59:45","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=913"},"modified":"2018-04-29T18:59:45","modified_gmt":"2018-04-29T16:59:45","slug":"salir-a-ganar","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2018\/04\/29\/salir-a-ganar\/","title":{"rendered":"Salir a ganar"},"content":{"rendered":"<p>Sin \u00e1nimo de pecar de gijonesista, atendiendo solo al inter\u00e9s general en favor de una universidad moderna y m\u00e1s competitiva, esta ciudad es la m\u00e1s capacitada para conseguir que los estudios de Ciencias del Deporte en Asturias puedan llegar a ser una referencia en el Norte de Espa\u00f1a. No es demagogia. Existen un c\u00famulo de razones que lo avalan: las instalaciones disponibles, la tradici\u00f3n en numerosas disciplinas, la colaboraci\u00f3n entre las entidades p\u00fablicas y privadas, los \u00e9xitos deportivos, un entorno favorable a la investigaci\u00f3n y al desarrollo de las nuevas tecnolog\u00edas y la aportaci\u00f3n financiera ofrecida por el Ayuntamiento, con el respaldo de todos los grupos pol\u00edticos locales, para implantar esta ense\u00f1anza.<br \/>\nDesde la parrilla de salida, su ubicaci\u00f3n en Gij\u00f3n es la garant\u00eda que tiene la Universidad de que la oferta de esta titulaci\u00f3n en su cat\u00e1logo de grados sea realmente atractiva, no solo para evitar la marcha de j\u00f3venes asturianos a otros lugares para cursar tales estudios, sino tambi\u00e9n para conseguir que vengan de afuera animados por todo el ecosistema que ofrece esta ciudad.<br \/>\nPero da la impresi\u00f3n de que en este tema se est\u00e1 renunciando, de mano, a la fuerza de un proyecto para salir a ganar. Cuesti\u00f3n incomprensible, por otro lado, dado el campo del que estamos hablando. El rector, con el respaldo del Consejo Social, defendi\u00f3 desde el primer momento que el grado de Deporte tuviera como sede el campus de Mieres para darle ocupaci\u00f3n a unas instalaciones hu\u00e9rfanas de actividad y de alumnado. Esta posici\u00f3n resulta entendible desde el punto de vista de la obligaci\u00f3n que tiene un gestor de aprovechar al m\u00e1ximo todos los recursos disponibles y que se encuentra con unas infraestructuras muertas, que costaron una millonada, producto de una visi\u00f3n distorsionada sobre las necesidades de las cuencas para la regeneraci\u00f3n del tejido econ\u00f3mico y social. El campus de Mieres ha sido un error, por no decir una cacicada m\u00e1s de las que se hicieron entonces, de tal manera que con el paso del tiempo se ha convertido en un problema may\u00fasculo para la propia universidad y para la regi\u00f3n. Si la construcci\u00f3n del centro universitario de Barredo fue una decisi\u00f3n absolutamente pol\u00edtica, ajena a los requerimientos acad\u00e9micos, la instalaci\u00f3n en ese lugar de esta nueva carrera por el imperioso cometido de tener que llevar all\u00ed alg\u00fan contenido tambi\u00e9n va camino de serlo.<br \/>\nAnte la antigua aspiraci\u00f3n de esta ciudad por dichos estudios, Mieres recurre ahora a la movilizaci\u00f3n para hacer valer su candidatura, planteada por cierto por una instituci\u00f3n privada, con todos los alcaldes de las cuencas al frente, los sindicatos mineros y el aval de algunos partidos a escala regional a la caza de votos. Es la historia de siempre. La pugna entre territorios que tanto da\u00f1o hizo a esta regi\u00f3n. El consejero de Infraestructuras dijo, a prop\u00f3sito de la ausencia del primer edil mierense en la reuni\u00f3n para avanzar sobre la creaci\u00f3n del \u00e1rea metropolitana, que este \u00f3rgano, si existiera, ser\u00eda el \u00e1mbito adecuado para resolver cuestiones como la que estamos tratando. Tiene raz\u00f3n el se\u00f1or Lastra. Si hace dos d\u00e9cadas hubiera funcionado una m\u00ednima coordinaci\u00f3n lo m\u00e1s probable es que hoy no estuvi\u00e9ramos hablando de aquel campus.<br \/>\nEntretanto, mientras en la localidad minera se preparan manifestaciones en la calle para reclamar el proyecto en el Caudal, en Gij\u00f3n disfrutamos de otro tipo de expresiones que, a la par, refuerzan la raz\u00f3n de la candidatura para una ense\u00f1anza p\u00fablica. Por ejemplo, la coincidencia en un mismo d\u00eda del otorgamiento de la medalla de oro de la villa al Hostelcur por sus brillantes \u00e9xitos europeos en el hockey sobre patines y de la celebraci\u00f3n en el balc\u00f3n del Ayuntamiento de la Copa de la Reina por las chicas del Mavi. Cu\u00e1ntas alegr\u00edas nos dan estas espl\u00e9ndidas deportistas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Sin \u00e1nimo de pecar de gijonesista, atendiendo solo al inter\u00e9s general en favor de una universidad moderna y m\u00e1s competitiva, esta ciudad es la m\u00e1s capacitada para conseguir que los estudios de Ciencias del Deporte en Asturias puedan llegar a ser una referencia en el Norte de Espa\u00f1a. No es demagogia. Existen un c\u00famulo de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[806,808,811,805,809,807,810,733,728],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/913"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=913"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/913\/revisions"}],"predecessor-version":[{"id":914,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/913\/revisions\/914"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}