{"id":944,"date":"2018-07-20T17:00:12","date_gmt":"2018-07-20T15:00:12","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=944"},"modified":"2018-07-20T17:00:12","modified_gmt":"2018-07-20T15:00:12","slug":"las-urgencias-de-las-tardes","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2018\/07\/20\/las-urgencias-de-las-tardes\/","title":{"rendered":"Las urgencias de las tardes"},"content":{"rendered":"<p>En 2010 se produjo la concentraci\u00f3n durante los fines de semana de los servicios de urgencias de los centros de salud de Gij\u00f3n en los mismos puntos que ahora plantearon los responsables sanitarios para todos los d\u00edas, con unos resultados mejores incluso de lo que entonces se esperaban. La calidad de la atenci\u00f3n aument\u00f3 al disponer en un mismo centro de m\u00e1s equipos de los que exist\u00edan hasta aquel momento, la correcta utilizaci\u00f3n de los dispositivos por parte de los usuarios mejor\u00f3 de manera notable al reducirse el factor comodidad en favor de la necesidad real de ir al m\u00e9dico y no se registr\u00f3 un incremento de la afluencia en los servicios de urgencias de Cabue\u00f1es o de Jove, como en un principio se lleg\u00f3 a temer. Aquella medida de ahorro, que supon\u00eda eliminar un servicio abierto en todos los centros desde hace casi tres d\u00e9cadas durante s\u00e1bados y domingos, funcion\u00f3 con un mejor aprovechamiento de los recursos profesionales entonces disponibles.<br \/>\nEl pasado mi\u00e9rcoles, los gestores sanitarios tuvieron que dar marcha atr\u00e1s a la unificaci\u00f3n en La Calzada, el Parque-Somi\u00f3, El Llano y Puerta de la Villa de la atenci\u00f3n diaria que se presta entre las tres y las ocho de la tarde en el resto de los centros de salud de la ciudad. La oposici\u00f3n vecinal, que representa en este caso la voz de los usuarios, impidi\u00f3 extender a toda la semana el proceso de concentraci\u00f3n en festivos que tan buen balance ofreci\u00f3 hace ocho a\u00f1os sin distorsiones ni deterioro alguno de los servicios. Los derechos adquiridos de los beneficiarios se impusieron al argumentario de los administradores de la sanidad p\u00fablica. La medida presentada por la gerencia se planteaba de forma temporal, como plan de choque ante la escasez de profesionales para hacer frente a las sustituciones derivadas del verano, pero los vecinos entendieron que se trataba de un recorte estival con efectos duraderos. Es decir, pasado el periodo lo que se cierra ahora no se vuelve a abrir. Quiz\u00e1s fue ese el error. Demasiada precipitaci\u00f3n para una acci\u00f3n de duraci\u00f3n corta y desgaste innecesario, cuando en el fondo se requiere una reorganizaci\u00f3n m\u00e1s profunda, meditada y con una intensa labor pedag\u00f3gica.<br \/>\nEl planteamiento ha sido retirado, pero no enterrado, seg\u00fan advirtieron sus promotores. Tarde o temprano se tendr\u00e1 que volver a poner sobre la mesa porque el modelo de urgencias en primaria, tal como est\u00e1 concebido ahora, ha perdido eficiencia en detrimento de la calidad de la atenci\u00f3n y de una cobertura eficaz de las necesidades del servicio. Las consultas por las tardes se han convertido, en la mayor\u00eda de los casos, en una prolongaci\u00f3n de las que tienen lugar por la ma\u00f1ana. Sobre todo en aquellos centros con una demanda asistencial m\u00e1s saturada, que han empezado a registrar demoras de varios d\u00edas para atender un simple dolor de garganta o de espalda. Si no me recibe mi m\u00e9dico por la ma\u00f1ana, acudo a urgencias por la tarde, aunque sea para renovar la receta. El sistema se ha pervertido y requiere soluciones para su correcci\u00f3n.<br \/>\nLa reagrupaci\u00f3n, bien proyectada, supondr\u00eda m\u00e1s beneficios que molestias para los usuarios. Claro que resulta inc\u00f3modo no tener el servicio a la puerta de casa, pero todav\u00eda es mucho m\u00e1s ingrato que, pese a ello, se tenga que aguardar la intemerata en la sala de espera porque el m\u00e9dico no d\u00e9 abasto o la consulta se encuentre vac\u00eda por el desplazamiento a un domicilio. La unificaci\u00f3n permitir\u00eda reforzar los equipos de las tardes en los centros seleccionados y, al mismo tiempo, destinar tambi\u00e9n recursos humanos a cubrir las ausencias producidas en las ma\u00f1anas por bajas o vacaciones, en ese deseo de evitar las demoras que ahora se est\u00e1n produciendo en la atenci\u00f3n primaria gijonesa.<br \/>\nEl modelo necesita una reestructuraci\u00f3n pensando en la sostenibilidad, en el incremento de la presi\u00f3n asistencial y en la excelencia del servicio. Tres objetivos en s\u00ed dif\u00edciles aunque no imposibles de compatibilizar, que solo se pueden conseguir con el consenso de todas las partes implicadas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En 2010 se produjo la concentraci\u00f3n durante los fines de semana de los servicios de urgencias de los centros de salud de Gij\u00f3n en los mismos puntos que ahora plantearon los responsables sanitarios para todos los d\u00edas, con unos resultados mejores incluso de lo que entonces se esperaban. La calidad de la atenci\u00f3n aument\u00f3 al [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/944"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=944"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/944\/revisions"}],"predecessor-version":[{"id":945,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/944\/revisions\/945"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}