{"id":972,"date":"2018-10-12T18:38:27","date_gmt":"2018-10-12T16:38:27","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/?p=972"},"modified":"2018-10-12T18:38:27","modified_gmt":"2018-10-12T16:38:27","slug":"jefatura-digital","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/2018\/10\/12\/jefatura-digital\/","title":{"rendered":"Jefatura digital"},"content":{"rendered":"<p>El dedo contin\u00faa siendo un instrumento muy utilizado en la actuaci\u00f3n pol\u00edtica en todas sus expresiones. No existe, al menos yo no conozco, representante p\u00fablico que no lo haya usado en determinado momento como herramienta de acci\u00f3n, unas veces a la manera acusadora, otras en modo reparto, para la asignaci\u00f3n de responsabilidades, premiar lealtades, realizar encargos o hasta designar candidatos. Lo hemos visto, lo seguimos viendo y todo parece indicar, nunca mejor dicho, que ser\u00e1 dif\u00edcil evitar que se siga apuntando con el \u00edndice pese a que en las normas de buena conducta est\u00e9 considerado un mal h\u00e1bito.<br \/>\nEl Tribunal Superior de Justicia de Asturias ha dado esta semana un golpe a la &#8216;dedocracia&#8217;, aunque ello no quiere decir que lleve a su exterminaci\u00f3n. La sala de lo contencioso administrativo obliga al Ayuntamiento de Gij\u00f3n a sacar a concurso un mont\u00f3n de jefaturas de servicio y secretar\u00edas de despacho, cincuenta y ocho en total, que el gobierno local ha ido cubriendo mediante nombramientos directos, sin pasar por ning\u00fan tipo de concurrencia, para ir conformando una elite funcionarial af\u00edn a los mandatarios locales.<br \/>\nLos afectados por la sentencia no son todos los que fueron designados mediante el se\u00f1alamiento a lo largo de estos \u00faltimos a\u00f1os. Solo aquellos que fueron elegidos a partir de febrero de 2016, poco antes de que el propio gobierno aceptara cumplir un mandato plenario para poner en marcha una reforma del aparato organizativo de la instituci\u00f3n municipal que pusiera punto final a una pr\u00e1ctica que pas\u00f3 a ser de uso com\u00fan conforme fue discurriendo el tiempo. Al parecer, los nombramientos a trav\u00e9s de este sistema se acerca al centenar si tenemos en cuenta todos los brazos de la administraci\u00f3n local, es decir, casi una legi\u00f3n dependiente de la junta gubernamental de turno que se constituye cada cuatro a\u00f1os. Resulta cuando menos sorprendente que un gobierno en minor\u00eda, d\u00e9bil en apoyos como ha sido tantas veces subrayado, haya sido capaz de tejer, as\u00ed como el que no quiere la cosa, una n\u00f3mina tan abultada de empleados de confianza.<br \/>\nDesde luego no se puede deducir que la pol\u00edtica laboral, en ese sentido, haya sido un fracaso. Se equivoca quien hace tal lectura porque el poder, al final, viene garantizado por el ej\u00e9rcito y los mandos aliados. Los responsables de la gesti\u00f3n municipal hicieron lo mismo que han venido realizando corporaciones anteriores con m\u00e1s respaldos para hacer y deshacer. El fallo judicial pone de manifiesto que existen todav\u00eda demasiados subterfugios para seguir aplicando el dedazo en una buena parte de los niveles de ocupaci\u00f3n de la administraci\u00f3n. En el caso que nos concierne, los cargos se fueron cubriendo a trav\u00e9s de comisiones de servicios, adscripciones temporales y libres designaciones sin recurrir a los procesos de selecci\u00f3n de personal mediante concurso que la legislaci\u00f3n prev\u00e9 para preservar los derechos de los empleados p\u00fablicos. Es decir, una manera de vulneraci\u00f3n que no es nueva bajo el sol. Por lo tanto, el Alto Tribunal anula todos esos nombramientos con un fallo que el Ayuntamiento est\u00e1 dispuesto a aceptar aunque vinculando el fin de la &#8216;jefatura digital&#8217; al Plan Reto, el proyecto que pondr\u00e1 orden a los puestos de trabajo y a las criterios para ocuparlos. Esa condici\u00f3n, sin embargo, encierra una peque\u00f1a trampa porque la negociaci\u00f3n de tal reestructuraci\u00f3n ser\u00e1 para el a\u00f1o que viene, es decir, aplicable por la pr\u00f3xima corporaci\u00f3n. Por lo tanto, el que venga detr\u00e1s que arree.<br \/>\nDec\u00eda un concejal que resulta dif\u00edcil hacer gesti\u00f3n si enfrente tienes a un funcionario que te pone mala cara. Y a buen seguro tiene raz\u00f3n, pero tampoco se trata de extender la politizaci\u00f3n aguas abajo. La raya debe quedar bien trazada.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El dedo contin\u00faa siendo un instrumento muy utilizado en la actuaci\u00f3n pol\u00edtica en todas sus expresiones. No existe, al menos yo no conozco, representante p\u00fablico que no lo haya usado en determinado momento como herramienta de acci\u00f3n, unas veces a la manera acusadora, otras en modo reparto, para la asignaci\u00f3n de responsabilidades, premiar lealtades, realizar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/972"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/comments?post=972"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/972\/revisions"}],"predecessor-version":[{"id":975,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/posts\/972\/revisions\/975"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/media?parent=972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/categories?post=972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/viento-nordeste\/wp-json\/wp\/v2\/tags?post=972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}